{"id":1166,"date":"2025-01-19T22:51:51","date_gmt":"2025-01-19T21:51:51","guid":{"rendered":"https:\/\/sfs.infosyslab.fr\/?page_id=1166"},"modified":"2026-07-21T13:35:40","modified_gmt":"2026-07-21T12:35:40","slug":"communaute-sfs","status":"publish","type":"page","link":"https:\/\/sfs.infosyslab.fr\/index.php\/la-sfs\/communaute-sfs\/","title":{"rendered":"Communaut\u00e9 SFS"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"has-medium-font-size wp-block-paragraph\"><strong>R\u00e9partition du lieu de travail des membres de la SFS, en France et en Europe : <\/strong><br><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">(<i>Attention, ceci ne refl\u00e8te que les membres ayant rempli leur fiche annuaire<\/i>)<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large is-resized\"><a href=\"https:\/\/sfs.infosyslab.fr\/wp-content\/uploads\/2026\/07\/carte_regions4.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"766\" src=\"https:\/\/sfs.infosyslab.fr\/wp-content\/uploads\/2026\/07\/carte_regions4-1024x766.jpg\" alt=\"\" class=\"wp-image-1516\" style=\"aspect-ratio:1.3368146953100677;width:666px;height:auto\" srcset=\"https:\/\/sfs.infosyslab.fr\/wp-content\/uploads\/2026\/07\/carte_regions4-1024x766.jpg 1024w, https:\/\/sfs.infosyslab.fr\/wp-content\/uploads\/2026\/07\/carte_regions4-300x224.jpg 300w, https:\/\/sfs.infosyslab.fr\/wp-content\/uploads\/2026\/07\/carte_regions4-768x575.jpg 768w, https:\/\/sfs.infosyslab.fr\/wp-content\/uploads\/2026\/07\/carte_regions4.jpg 1450w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n<\/div>\n\n\n<p class=\"has-small-font-size wp-block-paragraph\">Donn\u00e9es repr\u00e9sentatives, non exhaustives issues \u00e0 partir des r\u00e9ponses des membres de la SFS ayant r\u00e9pondu au questionnaire d\u00e9di\u00e9.<\/p>\n\n\n\n<p class=\"has-medium-font-size wp-block-paragraph\"><br><strong>Liste des laboratoires et des organismes o\u00f9 travaillent les membres de la SFS : <\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<figure class=\"wp-block-table is-style-regular\"><table class=\"has-white-color has-white-background-color has-text-color has-background has-link-color has-fixed-layout\">\n<table><tbody><tr><td><a href=\"https:\/\/isyeb.mnhn.fr\/fr\">Institut de Syst\u00e9matique, \u00c9volution, Biodiversit\u00e9 (UMR 7205)<\/a><\/td><\/tr><tr><td><a href=\"https:\/\/ecoanthropologie.fr\/fr\">\u00c9co-Anthropologie (UMR 7206)<\/a><\/td><\/tr><tr><td><a href=\"https:\/\/paleo.mnhn.fr\/fr\/presentation-du-cr2p-346\">Centre de recherche en pal\u00e9ontologie (UMR 7207)<\/a><\/td><\/tr><tr><td><a href=\"https:\/\/borea.mnhn.fr\/fr\">Biologie des organismes et des \u00e9cosyst\u00e8mes aquatiques (UMR 7208)<\/a><\/td><\/tr><tr><td><a href=\"https:\/\/hnhp.mnhn.fr\/fr\">Histoire Naturelle des Humanit\u00e9s Pr\u00e9historiques (UMR 7194)<\/a><\/td><\/tr><tr><td><a href=\"https:\/\/ecobio.univ-rennes.fr\/\">\u00c9cosyst\u00e8mes, Biodiversit\u00e9, \u00c9volution (UMR 6553)<\/a><\/td><\/tr><tr><td><a href=\"https:\/\/ihpst.pantheonsorbonne.fr\/\">Institut d&#8217;Histoire et de Philosophie des Sciences et des Techniques (UMR 8590)<\/a><\/td><\/tr><tr><td><a href=\"https:\/\/republique-des-savoirs.fr\/\">R\u00e9publique des savoirs (UMR 8241)<\/a><\/td><\/tr><tr><td><a href=\"https:\/\/www.umr-decod.fr\/fr\">Dynamique et durabilit\u00e9 des \u00e9cosyst\u00e8mes : de la source \u00e0 l&#8217;oc\u00e9an (UMR 0985)<\/a><\/td><\/tr><tr><td><a href=\"https:\/\/irhs.angers-nantes.hub.inrae.fr\/\">Institut de Recherches en Horticulture et Semences (UMR 1345)<\/a><\/td><\/tr><tr><td><a href=\"https:\/\/igepp.hub.inrae.fr\/\">Institut de G\u00e9n\u00e9tique pour l&#8217;Environnement et la Prot\u00e9ction des Plantes (UMR 1349)<\/a><\/td><\/tr><tr><td><a href=\"https:\/\/www.naturalsciences.be\/fr\/science\">Direction Op\u00e9rationnelle (D.O.) Taxonomie et Phylog\u00e9nie &#8211; Institut des Sciences Naturelles<\/a><\/td><\/tr><tr><td><a href=\"https:\/\/ebe.ulb.ac.be\/ebe\/ebe-Welcome.html\" data-type=\"link\" data-id=\"https:\/\/ebe.ulb.ac.be\/ebe\/ebe-Welcome.html\">Unit\u00e9 \u00c9volution Biologique et \u00c9cologie<\/a><\/td><\/tr><\/tbody<\/table><\/figure>\n\n\n\n<figure class=\"wp-block-table is-style-regular\"><table class=\"has-white-color has-white-background-color has-text-color has-background has-link-color has-fixed-layout\"><tbody><tr><td><a href=\"https:\/\/www.mnhn.fr\/fr\">Mus\u00e9um national d&#8217;Histoire naturelle<\/a><\/td><\/tr><tr><td><a href=\"https:\/\/www.sorbonne-universite.fr\/\">Sorbonne Universit\u00e9<\/a><\/td><\/tr><tr><td><a href=\"https:\/\/www.cnrs.fr\/fr\">Centre national de la recherche scientifique (CNRS)<\/a><\/td><\/tr><tr><td><a href=\"https:\/\/www.inrae.fr\/\">Institut national de recherche pour l&#8217;agriculture, l&#8217;alimentation et l&#8217;environnement (INRAE)<\/a><\/td><\/tr><tr><td><a href=\"https:\/\/www.institut-agro-rennes-angers.fr\/\">Institut Agro Rennes-Angers<\/a><\/td><\/tr><tr><td><a href=\"https:\/\/www.naturalsciences.be\/fr\">Institut Royal des Sciences Naturelles de Belgique<\/a><\/td><\/tr><tr><td><a href=\"https:\/\/www.umontpellier.fr\/\">Universit\u00e9 de Montpellier<\/a><\/td><\/tr><tr><td><a href=\"https:\/\/www.univ-rennes.fr\/\">Universit\u00e9 de Rennes<\/a><\/td><\/tr><tr><td><a href=\"https:\/\/www.pantheonsorbonne.fr\/\">Universit\u00e9 Paris 1 Panth\u00e9on-Sorbonne<\/a><\/td><\/tr><tr><td><a href=\"https:\/\/museum.var.fr\/ws\/home\/app\/collection\/expo\">Mus\u00e9um d\u00e9partemental du Var<\/a><\/td><\/tr><tr><td><a href=\"https:\/\/academie-veterinaire.fr\/\">Acad\u00e9mie v\u00e9t\u00e9rinaire de France<\/a><\/td><\/tr><tr><td><a href=\"https:\/\/cen-paca.org\/\">Conservatoire d&#8217;espaces naturels Provence-Alpes-C\u00f4te d&#8217;Azur (CEN PACA)<\/a><\/td><\/tr><tr><td><a href=\"https:\/\/www.ulb.be\/\">Universit\u00e9 libre de Bruxelles (ULB)<\/a><\/td><\/tr><tr><td><a href=\"https:\/\/www.uio.no\/english\/\">Universit\u00e9 d&#8217;Oslo<\/a><\/td><\/tr><tr><td><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-black-color\">Coll\u00e8ge Raymond Loewy (23 Creuse)<\/mark> (<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>R\u00e9partition du lieu de travail des membres de la SFS, en France et en Europe : (Attention, ceci ne refl\u00e8te que les membres ayant rempli leur fiche annuaire) Donn\u00e9es repr\u00e9sentatives, non exhaustives issues \u00e0 partir des r\u00e9ponses des membres de la SFS ayant r\u00e9pondu au questionnaire d\u00e9di\u00e9. Liste des laboratoires et des organismes o\u00f9 travaillent [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":19,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_monsterinsights_skip_tracking":false,"footnotes":""},"class_list":["post-1166","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/sfs.infosyslab.fr\/index.php\/wp-json\/wp\/v2\/pages\/1166","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sfs.infosyslab.fr\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/sfs.infosyslab.fr\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/sfs.infosyslab.fr\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/sfs.infosyslab.fr\/index.php\/wp-json\/wp\/v2\/comments?post=1166"}],"version-history":[{"count":40,"href":"https:\/\/sfs.infosyslab.fr\/index.php\/wp-json\/wp\/v2\/pages\/1166\/revisions"}],"predecessor-version":[{"id":1539,"href":"https:\/\/sfs.infosyslab.fr\/index.php\/wp-json\/wp\/v2\/pages\/1166\/revisions\/1539"}],"up":[{"embeddable":true,"href":"https:\/\/sfs.infosyslab.fr\/index.php\/wp-json\/wp\/v2\/pages\/19"}],"wp:attachment":[{"href":"https:\/\/sfs.infosyslab.fr\/index.php\/wp-json\/wp\/v2\/media?parent=1166"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}